{"id":14,"date":"2024-02-17T07:57:05","date_gmt":"2024-02-17T07:57:05","guid":{"rendered":"https:\/\/cfiler.com\/?page_id=14"},"modified":"2024-03-26T20:04:05","modified_gmt":"2024-03-26T20:04:05","slug":"faq","status":"publish","type":"page","link":"https:\/\/cfiler.com\/index.php\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f01ba17 e-flex e-con-boxed e-con e-parent\" data-id=\"f01ba17\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a11fa75 e-con-full e-flex e-con e-child\" data-id=\"a11fa75\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00b6cca elementor-widget elementor-widget-heading\" data-id=\"00b6cca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76902fd e-flex e-con-boxed e-con e-parent\" data-id=\"76902fd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb2899 elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"8bb2899\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1461\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1461\" aria-expanded=\"false\">Compliance<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1462\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1462\" aria-expanded=\"false\"> Pricing, Fees, & Refunds<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1463\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1463\" aria-expanded=\"false\">Banking<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1464\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1464\" aria-expanded=\"false\"> Order Information<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1461\" aria-expanded=\"false\">Compliance<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1461\" tabindex=\"0\" hidden=\"false\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"561\" class=\"elementor elementor-561\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-815bec2 e-flex e-con-boxed e-con e-parent\" data-id=\"815bec2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f285ee7 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"f285ee7\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04b63b38e0e\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-f285ee7\">\n                        <a href=\"#collapse-5dea4f66a04b63b38e0e\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5dea4f66a04b63b38e0e\" aria-expanded=\"true\" aria-controls=\"Collapse-5dea4f66a04b63b38e0e\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to visit the USA to open a bank account?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5dea4f66a04b63b38e0e\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-f285ee7\" data-parent=\"#accordion-6a04b63b38e0e\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, we manage all tasks remotely. You only need to provide your passport for identity verification, and we&#8217;ll handle the rest by working directly with the bank to open your account.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-f285ee7\">\n                        <a href=\"#collapse-4f673d26a04b63b38e0e\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f673d26a04b63b38e0e\" aria-expanded=\"false\" aria-controls=\"Collapse-4f673d26a04b63b38e0e\">\n                            \n                            <span class=\"ekit-accordion-title\">Do you help with taxes?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f673d26a04b63b38e0e\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-f285ee7\" data-parent=\"#accordion-6a04b63b38e0e\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We collaborate with our partners to offer a seamless tax filing experience for you. Through our partner, Bookmate, we offer packages tailored to your revenue and can handle filings for any entity compatible with Cfiler. As a Cfiler customer, you can enjoy an exclusive 10% discount on all Bookmate services. Federal tax returns are typically due in March or April, depending on the entity.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-f285ee7\">\n                        <a href=\"#collapse-dbdfab96a04b63b38e0e\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-dbdfab96a04b63b38e0e\" aria-expanded=\"false\" aria-controls=\"Collapse-dbdfab96a04b63b38e0e\">\n                            \n                            <span class=\"ekit-accordion-title\">What do I need to get started?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-dbdfab96a04b63b38e0e\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-f285ee7\" data-parent=\"#accordion-6a04b63b38e0e\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Fill out the form and we&#8217;ll be in touch shortly. Alternatively, you can reach us directly via WhatsApp.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-f285ee7\">\n                        <a href=\"#collapse-168c79d6a04b63b38e0e\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-168c79d6a04b63b38e0e\" aria-expanded=\"false\" aria-controls=\"Collapse-168c79d6a04b63b38e0e\">\n                            \n                            <span class=\"ekit-accordion-title\">What is the difference between using you and an expensive lawyer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-168c79d6a04b63b38e0e\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-f285ee7\" data-parent=\"#accordion-6a04b63b38e0e\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We offer more than traditional legal services at significantly lower costs, thanks to our utilization of technology and automation to streamline administrative expenses. Concerned about accuracy? Rest assured, our procedures undergo thorough validation by legal experts to ensure precise filing of your information.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-f285ee7\">\n                        <a href=\"#collapse-3d3d64a6a04b63b38e0e\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3d3d64a6a04b63b38e0e\" aria-expanded=\"false\" aria-controls=\"Collapse-3d3d64a6a04b63b38e0e\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to be a U.S. Citizen with an SSN to use Cfiler?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3d3d64a6a04b63b38e0e\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-f285ee7\" data-parent=\"#accordion-6a04b63b38e0e\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, you don&#8217;t need to be a U.S. Citizen with an SSN to use Cfiler. We support non-residents from over 175+ countries. If you do have an SSN, let us know and we can expedite your application.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1462\" aria-expanded=\"false\"> Pricing, Fees, & Refunds<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1462\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1462\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"575\" class=\"elementor elementor-575\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-815bec2 e-flex e-con-boxed e-con e-parent\" data-id=\"815bec2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f285ee7 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"f285ee7\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04b63b39ee4\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-f285ee7\">\n                        <a href=\"#collapse-5dea4f66a04b63b39ee4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5dea4f66a04b63b39ee4\" aria-expanded=\"true\" aria-controls=\"Collapse-5dea4f66a04b63b39ee4\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to visit the USA to open a bank account?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5dea4f66a04b63b39ee4\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-f285ee7\" data-parent=\"#accordion-6a04b63b39ee4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, we manage all tasks remotely. You only need to provide your passport for identity verification, and we&#8217;ll handle the rest by working directly with the bank to open your account.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-f285ee7\">\n                        <a href=\"#collapse-4f673d26a04b63b39ee4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f673d26a04b63b39ee4\" aria-expanded=\"false\" aria-controls=\"Collapse-4f673d26a04b63b39ee4\">\n                            \n                            <span class=\"ekit-accordion-title\">Do you help with taxes?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f673d26a04b63b39ee4\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-f285ee7\" data-parent=\"#accordion-6a04b63b39ee4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We collaborate with our partners to offer a seamless tax filing experience for you. Through our partner, Bookmate, we offer packages tailored to your revenue and can handle filings for any entity compatible with Cfiler. As a Cfiler customer, you can enjoy an exclusive 10% discount on all Bookmate services. Federal tax returns are typically due in March or April, depending on the entity.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-f285ee7\">\n                        <a href=\"#collapse-dbdfab96a04b63b39ee4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-dbdfab96a04b63b39ee4\" aria-expanded=\"false\" aria-controls=\"Collapse-dbdfab96a04b63b39ee4\">\n                            \n                            <span class=\"ekit-accordion-title\">What do I need to get started?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-dbdfab96a04b63b39ee4\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-f285ee7\" data-parent=\"#accordion-6a04b63b39ee4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Fill out the form and we&#8217;ll be in touch shortly. Alternatively, you can reach us directly via WhatsApp.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-f285ee7\">\n                        <a href=\"#collapse-168c79d6a04b63b39ee4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-168c79d6a04b63b39ee4\" aria-expanded=\"false\" aria-controls=\"Collapse-168c79d6a04b63b39ee4\">\n                            \n                            <span class=\"ekit-accordion-title\">What is the difference between using you and an expensive lawyer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-168c79d6a04b63b39ee4\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-f285ee7\" data-parent=\"#accordion-6a04b63b39ee4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We offer more than traditional legal services at significantly lower costs, thanks to our utilization of technology and automation to streamline administrative expenses. Concerned about accuracy? Rest assured, our procedures undergo thorough validation by legal experts to ensure precise filing of your information.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-f285ee7\">\n                        <a href=\"#collapse-3d3d64a6a04b63b39ee4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3d3d64a6a04b63b39ee4\" aria-expanded=\"false\" aria-controls=\"Collapse-3d3d64a6a04b63b39ee4\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to be a U.S. Citizen with an SSN to use Cfiler?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3d3d64a6a04b63b39ee4\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-f285ee7\" data-parent=\"#accordion-6a04b63b39ee4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, you don&#8217;t need to be a U.S. Citizen with an SSN to use Cfiler. We support non-residents from over 175+ countries. If you do have an SSN, let us know and we can expedite your application.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1463\" aria-expanded=\"false\">Banking<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1463\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1463\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"580\" class=\"elementor elementor-580\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-815bec2 e-flex e-con-boxed e-con e-parent\" data-id=\"815bec2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f285ee7 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"f285ee7\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04b63b3ab89\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-f285ee7\">\n                        <a href=\"#collapse-5dea4f66a04b63b3ab89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5dea4f66a04b63b3ab89\" aria-expanded=\"true\" aria-controls=\"Collapse-5dea4f66a04b63b3ab89\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to visit the USA to open a bank account?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5dea4f66a04b63b3ab89\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-f285ee7\" data-parent=\"#accordion-6a04b63b3ab89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, we manage all tasks remotely. You only need to provide your passport for identity verification, and we&#8217;ll handle the rest by working directly with the bank to open your account.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-f285ee7\">\n                        <a href=\"#collapse-4f673d26a04b63b3ab89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f673d26a04b63b3ab89\" aria-expanded=\"false\" aria-controls=\"Collapse-4f673d26a04b63b3ab89\">\n                            \n                            <span class=\"ekit-accordion-title\">Do you help with taxes?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f673d26a04b63b3ab89\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-f285ee7\" data-parent=\"#accordion-6a04b63b3ab89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We collaborate with our partners to offer a seamless tax filing experience for you. Through our partner, Bookmate, we offer packages tailored to your revenue and can handle filings for any entity compatible with Cfiler. As a Cfiler customer, you can enjoy an exclusive 10% discount on all Bookmate services. Federal tax returns are typically due in March or April, depending on the entity.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-f285ee7\">\n                        <a href=\"#collapse-dbdfab96a04b63b3ab89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-dbdfab96a04b63b3ab89\" aria-expanded=\"false\" aria-controls=\"Collapse-dbdfab96a04b63b3ab89\">\n                            \n                            <span class=\"ekit-accordion-title\">What do I need to get started?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-dbdfab96a04b63b3ab89\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-f285ee7\" data-parent=\"#accordion-6a04b63b3ab89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Fill out the form and we&#8217;ll be in touch shortly. Alternatively, you can reach us directly via WhatsApp.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-f285ee7\">\n                        <a href=\"#collapse-168c79d6a04b63b3ab89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-168c79d6a04b63b3ab89\" aria-expanded=\"false\" aria-controls=\"Collapse-168c79d6a04b63b3ab89\">\n                            \n                            <span class=\"ekit-accordion-title\">What is the difference between using you and an expensive lawyer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-168c79d6a04b63b3ab89\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-f285ee7\" data-parent=\"#accordion-6a04b63b3ab89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We offer more than traditional legal services at significantly lower costs, thanks to our utilization of technology and automation to streamline administrative expenses. Concerned about accuracy? Rest assured, our procedures undergo thorough validation by legal experts to ensure precise filing of your information.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-f285ee7\">\n                        <a href=\"#collapse-3d3d64a6a04b63b3ab89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3d3d64a6a04b63b3ab89\" aria-expanded=\"false\" aria-controls=\"Collapse-3d3d64a6a04b63b3ab89\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to be a U.S. Citizen with an SSN to use Cfiler?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3d3d64a6a04b63b3ab89\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-f285ee7\" data-parent=\"#accordion-6a04b63b3ab89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, you don&#8217;t need to be a U.S. Citizen with an SSN to use Cfiler. We support non-residents from over 175+ countries. If you do have an SSN, let us know and we can expedite your application.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1464\" aria-expanded=\"false\"> Order Information<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1464\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1464\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"585\" class=\"elementor elementor-585\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-815bec2 e-flex e-con-boxed e-con e-parent\" data-id=\"815bec2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f285ee7 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"f285ee7\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04b63b3b8a4\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-f285ee7\">\n                        <a href=\"#collapse-5dea4f66a04b63b3b8a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5dea4f66a04b63b3b8a4\" aria-expanded=\"true\" aria-controls=\"Collapse-5dea4f66a04b63b3b8a4\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to visit the USA to open a bank account?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5dea4f66a04b63b3b8a4\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-f285ee7\" data-parent=\"#accordion-6a04b63b3b8a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, we manage all tasks remotely. You only need to provide your passport for identity verification, and we&#8217;ll handle the rest by working directly with the bank to open your account.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-f285ee7\">\n                        <a href=\"#collapse-4f673d26a04b63b3b8a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f673d26a04b63b3b8a4\" aria-expanded=\"false\" aria-controls=\"Collapse-4f673d26a04b63b3b8a4\">\n                            \n                            <span class=\"ekit-accordion-title\">Do you help with taxes?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f673d26a04b63b3b8a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-f285ee7\" data-parent=\"#accordion-6a04b63b3b8a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We collaborate with our partners to offer a seamless tax filing experience for you. Through our partner, Bookmate, we offer packages tailored to your revenue and can handle filings for any entity compatible with Cfiler. As a Cfiler customer, you can enjoy an exclusive 10% discount on all Bookmate services. Federal tax returns are typically due in March or April, depending on the entity.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-f285ee7\">\n                        <a href=\"#collapse-dbdfab96a04b63b3b8a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-dbdfab96a04b63b3b8a4\" aria-expanded=\"false\" aria-controls=\"Collapse-dbdfab96a04b63b3b8a4\">\n                            \n                            <span class=\"ekit-accordion-title\">What do I need to get started?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-dbdfab96a04b63b3b8a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-f285ee7\" data-parent=\"#accordion-6a04b63b3b8a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Fill out the form and we&#8217;ll be in touch shortly. Alternatively, you can reach us directly via WhatsApp.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-f285ee7\">\n                        <a href=\"#collapse-168c79d6a04b63b3b8a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-168c79d6a04b63b3b8a4\" aria-expanded=\"false\" aria-controls=\"Collapse-168c79d6a04b63b3b8a4\">\n                            \n                            <span class=\"ekit-accordion-title\">What is the difference between using you and an expensive lawyer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-168c79d6a04b63b3b8a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-f285ee7\" data-parent=\"#accordion-6a04b63b3b8a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We offer more than traditional legal services at significantly lower costs, thanks to our utilization of technology and automation to streamline administrative expenses. Concerned about accuracy? Rest assured, our procedures undergo thorough validation by legal experts to ensure precise filing of your information.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-f285ee7\">\n                        <a href=\"#collapse-3d3d64a6a04b63b3b8a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3d3d64a6a04b63b3b8a4\" aria-expanded=\"false\" aria-controls=\"Collapse-3d3d64a6a04b63b3b8a4\">\n                            \n                            <span class=\"ekit-accordion-title\">Do I need to be a U.S. Citizen with an SSN to use Cfiler?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3d3d64a6a04b63b3b8a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-f285ee7\" data-parent=\"#accordion-6a04b63b3b8a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>No, you don&#8217;t need to be a U.S. Citizen with an SSN to use Cfiler. We support non-residents from over 175+ countries. If you do have an SSN, let us know and we can expedite your application.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18a1a73 e-flex e-con-boxed e-con e-parent\" data-id=\"18a1a73\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c0dd74d e-con-full e-flex e-con e-child\" data-id=\"c0dd74d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f9359a elementor-widget elementor-widget-heading\" data-id=\"0f9359a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GLOBAL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b3059e elementor-widget elementor-widget-heading\" data-id=\"3b3059e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Excited to begin your dream business journey?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c83f11f elementor-widget elementor-widget-text-editor\" data-id=\"c83f11f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Don&#8217;t Wait! Hundreds of entrepreneurs have already launched their businesses!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f05411 e-flex e-con-boxed e-con e-child\" data-id=\"2f05411\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32e7c3a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"32e7c3a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Started<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQs Compliance Pricing, Fees, &#038; Refunds Banking Order Information Compliance Do I need to visit the USA to open a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"_links":{"self":[{"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/pages\/14"}],"collection":[{"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":40,"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":1486,"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions\/1486"}],"wp:attachment":[{"href":"https:\/\/cfiler.com\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}